{"id":836,"date":"2024-05-23T09:19:06","date_gmt":"2024-05-23T07:19:06","guid":{"rendered":"https:\/\/www.brmultiservizi.it\/blog\/?p=836"},"modified":"2024-06-07T11:29:08","modified_gmt":"2024-06-07T09:29:08","slug":"interdizione-parcheggio-low-cost-p8-brindisi-casale","status":"publish","type":"post","link":"https:\/\/www.brmultiservizi.it\/blog\/2024\/05\/23\/interdizione-parcheggio-low-cost-p8-brindisi-casale\/","title":{"rendered":"Interdizione Parcheggio Low Cost P8 &#8211; Brindisi Casale"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-842\" src=\"https:\/\/www.brmultiservizi.it\/blog\/wp-content\/uploads\/ParkP8.jpg\" alt=\"\" width=\"1000\" height=\"563\" srcset=\"https:\/\/www.brmultiservizi.it\/blog\/wp-content\/uploads\/ParkP8.jpg 1000w, https:\/\/www.brmultiservizi.it\/blog\/wp-content\/uploads\/ParkP8-300x169.jpg 300w, https:\/\/www.brmultiservizi.it\/blog\/wp-content\/uploads\/ParkP8-768x432.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/p>\r\n<p>Si comunica che, vista l&#8217;ordinanza dirigenziale del settore LL.PP. &#8211; Comune di Brindisi n. 267 del 06\/06\/2024, che dispone <em>il divieto di transito e di sosta della viabilit\u00e0 che adduce alla chiesa &#8220;Santa Maria del Casale&#8221;<\/em> <strong>dalle ore 7:00 del giorno 11\/06\/2024 sino alle ore <\/strong><strong>14:00<\/strong><strong> del 16\/06\/2024<\/strong>, l&#8217;area di sosta <strong>&#8220;Parcheggio Low Cost P8 &#8211; Brindisi Casale&#8221; <\/strong>non sar\u00e0 utilizzabile in tale periodo.<\/p>\r\n<p>Il parcheggio sar\u00e0 pertanto interdetto ed i mezzi ivi rinvenuti saranno oggetto di <strong>rimozione coatta<\/strong>.<\/p>\r\n<p>Il presente avviso sar\u00e0 affisso all&#8217;ingresso del parcheggio e nei pressi dell&#8217;area.<\/p>\r\n<p><a href=\"https:\/\/www.brmultiservizi.it\/blog\/wp-content\/uploads\/OD_232_2024.pdf\">Ordinanza Dirigenziale_232_2024<\/a><\/p>\r\n<p><a href=\"https:\/\/www.brmultiservizi.it\/blog\/wp-content\/uploads\/OD_255_2024.pdf\">Ordinanza Dirigenziale_255_2024<\/a><\/p>\r\n<p><a href=\"https:\/\/www.brmultiservizi.it\/blog\/wp-content\/uploads\/OD_267_2024.pdf\">Ordinanza Dirigenziale_267_2024<\/a><\/p>\r\n\r\n<p><iframe loading=\"lazy\" style=\"border: 0;\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m14!1m12!1m3!1d1049.7488005228493!2d17.935125188648257!3d40.65503099009795!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!5e0!3m2!1sit!2sit!4v1716449631034!5m2!1sit!2sit\" width=\"600\" height=\"450\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Si comunica che, vista l&#8217;ordinanza dirigenziale del settore LL.PP. &#8211; Comune di Brindisi n. 267 del 06\/06\/2024, che dispone il divieto di transito e di sosta della viabilit\u00e0 che adduce alla chiesa &#8220;Santa Maria&#46;&#46;&#46;<\/p>\n","protected":false},"author":1,"featured_media":842,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-836","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-avvisi"],"_links":{"self":[{"href":"https:\/\/www.brmultiservizi.it\/blog\/wp-json\/wp\/v2\/posts\/836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.brmultiservizi.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brmultiservizi.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brmultiservizi.it\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brmultiservizi.it\/blog\/wp-json\/wp\/v2\/comments?post=836"}],"version-history":[{"count":10,"href":"https:\/\/www.brmultiservizi.it\/blog\/wp-json\/wp\/v2\/posts\/836\/revisions"}],"predecessor-version":[{"id":852,"href":"https:\/\/www.brmultiservizi.it\/blog\/wp-json\/wp\/v2\/posts\/836\/revisions\/852"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brmultiservizi.it\/blog\/wp-json\/wp\/v2\/media\/842"}],"wp:attachment":[{"href":"https:\/\/www.brmultiservizi.it\/blog\/wp-json\/wp\/v2\/media?parent=836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brmultiservizi.it\/blog\/wp-json\/wp\/v2\/categories?post=836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brmultiservizi.it\/blog\/wp-json\/wp\/v2\/tags?post=836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}